

{"id":833,"date":"2023-05-05T15:10:00","date_gmt":"2023-05-05T18:10:00","guid":{"rendered":"https:\/\/museu.appoa.org.br\/site\/?post_type=acontecimento&#038;p=833"},"modified":"2023-05-22T17:36:44","modified_gmt":"2023-05-22T20:36:44","slug":"belo-monte-a-conversao-de-pessoas-floresta-em-pobres-com-eliane-brum","status":"publish","type":"acontecimento","link":"https:\/\/museu.appoa.org.br\/site\/acontecimento\/belo-monte-a-conversao-de-pessoas-floresta-em-pobres-com-eliane-brum\/","title":{"rendered":"Belo Monte: a convers\u00e3o de pessoas-floresta em pobres &#8211; com Eliane Brum"},"content":{"rendered":"\n<p>Nesta pr\u00f3xima quinta-feira (18 de maio), \u00e0s 15h, durante a programa\u00e7\u00e3o da 21\u00aa Semana Nacional de Museus, o Museu das Mem\u00f3rias (<em>In<\/em>)Poss\u00edveis revisita sua exposi\u00e7\u00e3o <a href=\"https:\/\/museu.appoa.org.br\/site\/exposicao-belo-monte\/\">&#8220;Belo Monte: viol\u00eancia e etnoc\u00eddio&#8221;<\/a> com a participa\u00e7\u00e3o de Eliane Brum. Durante o encontro, a jornalista, escritora e documentarista ir\u00e1 falar sobre &#8220;Belo Monte: a convers\u00e3o de pessoas-floresta em pobres&#8221;.&nbsp;<\/p>\n\n\n\n<p>Idealizada na d\u00e9cada de 80, desde a sua constru\u00e7\u00e3o, em junho de 2011, a Usina Belo Monte tem provocado uma s\u00e9rie de protestos e ocupa\u00e7\u00f5es por ambientalistas e moradores da regi\u00e3o e de interven\u00e7\u00f5es de institui\u00e7\u00f5es p\u00fablicas, entre elas o Minist\u00e9rio P\u00fablico. Naquele momento, j\u00e1 eram evidentes seus impactos ambientais e danos \u00e0s popula\u00e7\u00f5es ind\u00edgenas e ribeirinhas. &nbsp;&nbsp;<\/p>\n\n\n\n<p>H\u00e1 sete anos, Eliane Brum deixou S\u00e3o Paulo e passou a residir em Altamira (Par\u00e1), cidade pr\u00f3xima a usina. Jornalista experiente, que trabalhou em v\u00e1rias publica\u00e7\u00f5es nacionais e europeias, vem denunciando as viol\u00eancias territoriais e defendendo a vida na regi\u00e3o Amaz\u00f5nica. Autora de v\u00e1rios livros, no mais recente&nbsp;<em>Banzeiro \u00d2k\u00f2t\u00f3: uma Viagem a Amaz\u00f4nia Centro do Mundo<\/em>, parte de observa\u00e7\u00f5es pessoais e de intensa investiga\u00e7\u00e3o jornal\u00edstica. Em 2022, junto com o marido Jonathan Watts, editor global de Meio Ambiente do jornal ingl\u00eas The Guardian, Eliane criou a plataforma global <a href=\"https:\/\/sumauma.com\">Suma\u00fama<\/a>, feita sob o olhar dos povos da floresta, para colocar a Amaz\u00f4nia no centro do jornalismo mundial.&nbsp;&nbsp; &nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Data: 18\/05\/2023<\/p>\n\n\n\n<p>Hor\u00e1rio: 15hs<\/p>\n\n\n\n<p>Evento online (Zoom) e gratuito mediante inscri\u00e7\u00e3o pr\u00e9via.<\/p>\n\n\n\n<p>Inscri\u00e7\u00f5es: appoa@appoa.org.br  <\/p>\n\n\n\n<p>Assista ao evento <a href=\"https:\/\/www.youtube.com\/watch?v=HXmCjxAKlTI&amp;t=692s\">aqui<\/a><\/p>\n","protected":false},"template":"","_links":{"self":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento\/833"}],"collection":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento"}],"about":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/types\/acontecimento"}],"wp:attachment":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/media?parent=833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}