

{"id":778,"date":"2022-12-02T16:30:56","date_gmt":"2022-12-02T19:30:56","guid":{"rendered":"https:\/\/museu.appoa.org.br\/site\/?post_type=acontecimento&#038;p=778"},"modified":"2022-12-02T16:30:57","modified_gmt":"2022-12-02T19:30:57","slug":"museu-no-5o-sebramus%ef%bf%bc","status":"publish","type":"acontecimento","link":"https:\/\/museu.appoa.org.br\/site\/acontecimento\/museu-no-5o-sebramus%ef%bf%bc\/","title":{"rendered":"Museu no 5\u00ba\u00a0SEBRAMUS\ufffc"},"content":{"rendered":"\n<p>O Museu das Mem\u00f3rias (<em>In<\/em>)Poss\u00edveis participar\u00e1 do <a href=\"https:\/\/www.ufrgs.br\/5sebramus\/\">5\u00ba Semin\u00e1rio Brasileiro de Museologia \u2013\u00a0<strong>Museologia em movimento: lutas e resist\u00eancias<\/strong><\/a> com o trabalho &#8220;<strong>Um museu virtual para as mem\u00f3rias do (<em>In<\/em>)poss\u00edvel: trauma, resist\u00eancia e interven\u00e7\u00e3o&#8221;<\/strong>.<\/p>\n\n\n\n<p><strong>Dia<\/strong>: 07\/12\/2022<\/p>\n\n\n\n<p><strong>Hora<\/strong>: 16:10<\/p>\n\n\n\n<p><strong>Onde<\/strong>: Faculdade de Biblioteconomia e Comunica\u00e7\u00e3o &#8211; Universidade Federal do Rio Grande do Sul (UFRGS)<\/p>\n\n\n\n<p>R. Ramiro Barcelos, 2705 &#8211; Santana, Porto Alegre &#8211; RS, 90035-007<\/p>\n","protected":false},"template":"","_links":{"self":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento\/778"}],"collection":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento"}],"about":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/types\/acontecimento"}],"wp:attachment":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/media?parent=778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}