

{"id":749,"date":"2022-10-21T21:42:38","date_gmt":"2022-10-22T00:42:38","guid":{"rendered":"https:\/\/museu.appoa.org.br\/site\/?post_type=acontecimento&#038;p=749"},"modified":"2022-10-21T21:43:54","modified_gmt":"2022-10-22T00:43:54","slug":"museu-no-psipolis","status":"publish","type":"acontecimento","link":"https:\/\/museu.appoa.org.br\/site\/acontecimento\/museu-no-psipolis\/","title":{"rendered":"Museu no PsiPolis"},"content":{"rendered":"\n<p>Na ter\u00e7a-feira (25 de outubro), das 14h30min \u00e0s 17h30min, a Psicanalista Ma\u00edra Brum Rieck \u00e9 a convidada do Grupo de Pesquisa PsiPolis para falar sobre o museu virtual Museu das Mem\u00f3rias (<em>In<\/em>)Poss\u00edveis.<\/p>\n\n\n\n<p> O encontro \u00e9 uma realiza\u00e7\u00e3o do Instituto de Estudos da Linguagem da Unicamp e \u00e9 aberto ao p\u00fablico. <\/p>\n\n\n\n<p>Assista ao evento <a href=\"https:\/\/www.youtube.com\/watch?v=U88qR_4drwM\">aqui<\/a> <\/p>\n","protected":false},"template":"","_links":{"self":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento\/749"}],"collection":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento"}],"about":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/types\/acontecimento"}],"wp:attachment":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/media?parent=749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}