

{"id":669,"date":"2022-07-08T17:37:17","date_gmt":"2022-07-08T20:37:17","guid":{"rendered":"https:\/\/museu.appoa.org.br\/site\/?post_type=acontecimento&#038;p=669"},"modified":"2022-08-02T10:07:31","modified_gmt":"2022-08-02T13:07:31","slug":"luis-carlos-toro-tamayo-no-gt-trauma-e-memoria","status":"publish","type":"acontecimento","link":"https:\/\/museu.appoa.org.br\/site\/acontecimento\/luis-carlos-toro-tamayo-no-gt-trauma-e-memoria\/","title":{"rendered":"Luis Carlos Toro Tamayo\u00a0no GT Trauma e Mem\u00f3ria"},"content":{"rendered":"\n<p>Luis Carlos Toro Tamayo da Universidade de Antioquia (Col\u00f4mbia)estar\u00e1 no Grupo de Trabalho Trauma e Mem\u00f3ria: interlocu\u00e7\u00f5es no dia 01 de agosto, \u00e0s 21 horas.<\/p>\n\n\n\n<p>Mais informa\u00e7\u00f5es: <a href=\"https:\/\/museu.appoa.org.br\/site\/events\/gt-trauma-e-memoria-agosto-2022\/\">aqui<\/a><\/p>\n\n\n\n<p>Conhe\u00e7a a exposi\u00e7\u00e3o <a href=\"http:\/\/memorialdaresistenciasp.org.br\/a-casa-um-lugar-de-memorias\/\">A CASA Um lugar de mem\u00f3rias<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"template":"","_links":{"self":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento\/669"}],"collection":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento"}],"about":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/types\/acontecimento"}],"wp:attachment":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/media?parent=669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}