

{"id":1256,"date":"2025-03-25T16:15:04","date_gmt":"2025-03-25T19:15:04","guid":{"rendered":"https:\/\/museu.appoa.org.br\/site\/?post_type=acontecimento&#038;p=1256"},"modified":"2025-04-07T23:54:25","modified_gmt":"2025-04-08T02:54:25","slug":"gt-trauma-e-memoria-com-elaine-milmann","status":"publish","type":"acontecimento","link":"https:\/\/museu.appoa.org.br\/site\/acontecimento\/gt-trauma-e-memoria-com-elaine-milmann\/","title":{"rendered":"GT Trauma e Mem\u00f3ria com Elaine Milmann"},"content":{"rendered":"\n<p>O Museu das Mem\u00f3rias (\ud835\ude10\ud835\ude2f)Poss\u00edveis promove o GRUPO DE TRABALHO &#8220;TRAUMA E MEM\u00d3RIA: INTERLOCU\u00c7\u00d5ES&#8221;.&nbsp;E, neste ano de 2025, vamos nos debru\u00e7ar sobre o tema das defici\u00eancias. Para trabalharmos este tema t\u00e3o complexo, pensamos ser importante formularmos algumas quest\u00f5es fundamentais.<\/p>\n\n\n\n<p>Nossa cultura est\u00e1 preparada para acolher aqueles sujeitos que n\u00e3o se enquadram em determinados par\u00e2metros? Como acolhemos as defici\u00eancias na nossa sociedade? O que significa &#8220;incluir&#8221; algu\u00e9m? Inclu\u00edmos na diferen\u00e7a ou tentamos achat\u00e1-la\/suprim\u00ed-la? Almejamos a &#8220;normaliza\u00e7\u00e3o&#8221;? Estamos sabendo escutar os sujeitos n\u00e3o somente na sua defici\u00eancia, mas nas suas singularidades? Qual \u00e9 a imagem que esses sujeitos t\u00eam de si mesmos? Como se v\u00eaem e como s\u00e3o vistos? O que temos a aprender com as defici\u00eancias?<\/p>\n\n\n\n<p>Os encontros ser\u00e3o virtuais, nas primeiras segundas-feiras de cada m\u00eas (come\u00e7ando em abril), \u00e0s 21hs e gratuitos (mediante inscri\u00e7\u00e3o). <\/p>\n\n\n\n<p>O primeiro encontro do ano acontecer\u00e1 dia 7 de abril \u00e0s 21h. E teremos a honra de receber Elaine Milmann, com a fala intitulada Diferen\u00e7a e la\u00e7o social: quem \u00e9 o sujeito da inclus\u00e3o?<\/p>\n\n\n\n<p><br>7\/04\/2025 | 21h <br>Evento Online<\/p>\n\n\n\n<p>Inscri\u00e7\u00f5es: <a href=\"mailto:appoa@appoa.org.br\">appoa@appoa.org.br<\/a><\/p>\n\n\n\n<p>Bio:<\/p>\n\n\n\n<p>&#8220;Sou Elaine Milmann, me formei em Educa\u00e7\u00e3o Especial em 1985 e depois me (trans)formei em psicopedagoga em 1989. Trabalhei na prefeitura de Porto Alegre nas d\u00e9cadas de 1990 e 2000 e acompanhei alguns movimentos educacionais hist\u00f3ricos, em uma caminhada que trago como horizonte a transforma\u00e7\u00e3o da escola para construirmos, juntes, uma Cultura inclusiva. Fiz mestrado e doutorado em Educa\u00e7\u00e3o pela UFRGS. Tamb\u00e9m realizei p\u00f3s-doutorado pela UFRGS e pela UL. Sigo como pesquisadora no NUPPEC\/UFRGS eixo-2 e coloco minhas lentes investigativas sobre a escrita e a linguagem.&#8221;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Grava\u00e7\u00e3o dispon\u00edvel no canal do Youtube do Museu<br>@MuseudasMemoriasInPossiveis<br>Link de acesso: <a href=\"https:\/\/youtu.be\/G7Iw6u0Pkic\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/youtu.be\/G7Iw6u0Pkic<\/a><\/p>\n","protected":false},"template":"","_links":{"self":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento\/1256"}],"collection":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento"}],"about":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/types\/acontecimento"}],"wp:attachment":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/media?parent=1256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}