

{"id":1209,"date":"2024-11-30T18:00:13","date_gmt":"2024-11-30T21:00:13","guid":{"rendered":"https:\/\/museu.appoa.org.br\/site\/?post_type=acontecimento&#038;p=1209"},"modified":"2024-11-30T18:14:07","modified_gmt":"2024-11-30T21:14:07","slug":"dos-esqueletos-no-guarda-roupa-aos-epigramas","status":"publish","type":"acontecimento","link":"https:\/\/museu.appoa.org.br\/site\/acontecimento\/dos-esqueletos-no-guarda-roupa-aos-epigramas\/","title":{"rendered":"Dos esqueletos no guarda-roupa aos epigramas"},"content":{"rendered":"\n<p>Lan\u00e7amento da exposi\u00e7\u00e3o &#8220;<strong>Dos esqueletos no guarda-roupa aos epigramas: uma jornada pelas mem\u00f3rias ocultas de Manoela Cavalinho<\/strong>&#8220;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>&#8220;Esqueletos no guarda-roupa&#8221;. Express\u00e3o que vem da l\u00edngua inglesa <em>skeleton in the closet. <\/em>Quais os segredos que as nossas fam\u00edlias escondem nos &#8220;arm\u00e1rios&#8221;? Quais hist\u00f3rias s\u00e3o escolhidas para serem contadas aos filhos? Quais s\u00e3o banidas? Quais s\u00e3o transmitidas?&nbsp;<\/p>\n\n\n\n<p>Sabemos que o que se transmite n\u00e3o \u00e9 somente o que \u00e9 dito. Sabemos que \u00e0s vezes os n\u00e3o ditos t\u00eam um poder de transmiss\u00e3o maior do que o que se pretende dizer. Sabemos que aquele que escuta pode escutar\/captar as inten\u00e7\u00f5es, os desvios, os sil\u00eancios, as lacunas. Sabemos que o inconsciente escuta o que n\u00e3o queria ser dito.&nbsp;<\/p>\n\n\n\n<p>Manoela escutou os esqueletos no guarda-roupa de sua fam\u00edlia. Escutou e n\u00e3o silenciou. O que significa silenciar? Ser c\u00famplice atrav\u00e9s do sil\u00eancio? Manoela criou a partir do horror, com seus epigramas.<\/p>\n\n\n\n<p>S\u00e3o muitas as perguntas. Qual a participa\u00e7\u00e3o de seu pai na ditadura? Ele torturou algu\u00e9m? Ele matou algu\u00e9m? Ele resistiu mesmo sendo policial?<\/p>\n\n\n\n<p>Mais do que de fatos ou provas concretas, a obra de Manoela fala do medo. Medo de ver e de n\u00e3o ver. Medo dos segredos e dos fantasmas de sua fam\u00edlia.&nbsp;<\/p>\n\n\n\n<p>Mas as perguntas e os medos de Manoela n\u00e3o s\u00e3o somente dela. Como brasileiros, todos temos nossos esqueletos nos nossos guarda-roupas. Nossos antepassados escravizaram ind\u00edgenas e negros? Nossos antepassados estupraram? Nossos antepassados torturaram?&nbsp;<\/p>\n\n\n\n<p>O que nos \u00e9 transmitido?&nbsp;<\/p>\n\n\n\n<p>O que fazemos com o que nos \u00e9 transmitido?<\/p>\n\n\n\n<p>Como n\u00e3o sermos c\u00famplices dos crimes do passado?<\/p>\n\n\n\n<p>N\u00f3s fomos beneficiados por crimes passados mesmo sem saber que fomos?<\/p>\n\n\n\n<p>Somos privilegiados pelo sangue de outros, de outras \u00e9pocas?<\/p>\n\n\n\n<p>Qual o nosso lugar na Hist\u00f3ria e como deixamos de transmitir o horror?<\/p>\n\n\n\n<p>Manoela, corajosa como \u00e9, escolheu n\u00e3o colocar os segredos da fam\u00edlia de volta no guarda-roupa. Escolheu abrir, escrever e inscrever com seus epigramas, saindo do particular da casa e indo para as ruas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Quando: 09\/12\/2024<\/strong><\/p>\n\n\n\n<p><strong>20hs<\/strong><\/p>\n\n\n\n<p><strong>Evento online e gratuito mediante inscri\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>appoa@appoa.org.br<\/strong><\/p>\n","protected":false},"template":"","_links":{"self":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento\/1209"}],"collection":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento"}],"about":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/types\/acontecimento"}],"wp:attachment":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/media?parent=1209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}