

{"id":1152,"date":"2024-08-12T22:47:19","date_gmt":"2024-08-13T01:47:19","guid":{"rendered":"https:\/\/museu.appoa.org.br\/site\/?post_type=acontecimento&#038;p=1152"},"modified":"2024-08-16T08:53:43","modified_gmt":"2024-08-16T11:53:43","slug":"gt-trauma-e-memoria-com-andreia-da-silva-daltoe","status":"publish","type":"acontecimento","link":"https:\/\/museu.appoa.org.br\/site\/acontecimento\/gt-trauma-e-memoria-com-andreia-da-silva-daltoe\/","title":{"rendered":"GT Trauma e Mem\u00f3ria com Andr\u00e9ia da Silva Dalto\u00e9"},"content":{"rendered":"\n<p>Desde 2019, o Museu das Mem\u00f3rias (\ud835\ude10\ud835\ude2f)Poss\u00edveis promove o GRUPO DE TRABALHO &#8220;TRAUMA E MEM\u00d3RIA: INTERLOCU\u00c7\u00d5ES&#8221;.&nbsp;<\/p>\n\n\n\n<p>Neste ano de 2024, estaremos com uma s\u00e9rie de eventos destinados a descomemorar os 60 anos do golpe empresarial-militar de 1964.&nbsp;<\/p>\n\n\n\n<p>Nossos encontros s\u00e3o todas as primeiras segundas-feiras de cada m\u00eas, \u00e0s 21hs, no formato online. S\u00e3o atividades abertas e gratuitas mediante inscri\u00e7\u00e3o.<\/p>\n\n\n\n<p>Em setembro temos a honra de receber Andr\u00e9ia da Silva Dalto\u00e9, com a fala intitulada <em>Comemorar, rememorar, descomemorar: Entre mem\u00f3ria e esquecimento, Ditadura e a disputa com\/por palavras<\/em>.&nbsp;<\/p>\n\n\n\n<p><strong>Resumo:<\/strong> Uma discuss\u00e3o sobre o modo como nossa rela\u00e7\u00e3o com a hist\u00f3ria da Ditadura e com a luta pol\u00edtica \u00e9 tamb\u00e9m uma rela\u00e7\u00e3o de disputa com\/por palavras. Comemorar, rememorar, descomemorar\u2026 palavras que engendram esquecimento e mem\u00f3ria, mostrando a necessidade de enfrentamentos no social que signifiquem o passado e ajudem num trabalho de educa\u00e7\u00e3o para o presente e futuro.<\/p>\n\n\n\n<p><strong>Biografia: <\/strong>Andr\u00e9ia da Silva Dalto\u00e9 \u00e9 licenciada em Letras pela UNISUL\/SC, onde tamb\u00e9m realizou Especializa\u00e7\u00e3o e Mestrado em Ci\u00eancias da Linguagem. Doutora em Letras pela UFRGS. Professora do Programa de P\u00f3s-Gradua\u00e7\u00e3o em Ci\u00eancias da Linguagem \u2013 PPGCL\/UNISUL.<\/p>\n\n\n\n<p>Quando? <br>2\/09\/2024 | 21h <br>Evento Online<\/p>\n\n\n\n<p>Inscri\u00e7\u00f5es: <a href=\"mailto:appoa@appoa.org.br\">appoa@appoa.org.br<\/a><\/p>\n","protected":false},"template":"","_links":{"self":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento\/1152"}],"collection":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento"}],"about":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/types\/acontecimento"}],"wp:attachment":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/media?parent=1152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}