

{"id":1130,"date":"2024-06-06T17:48:30","date_gmt":"2024-06-06T20:48:30","guid":{"rendered":"https:\/\/museu.appoa.org.br\/site\/?post_type=acontecimento&#038;p=1130"},"modified":"2024-06-06T17:48:31","modified_gmt":"2024-06-06T20:48:31","slug":"gt-trauma-e-memoria-com-cristina-pozzobon-2","status":"publish","type":"acontecimento","link":"https:\/\/museu.appoa.org.br\/site\/acontecimento\/gt-trauma-e-memoria-com-cristina-pozzobon-2\/","title":{"rendered":"GT Trauma e Mem\u00f3ria com Cristina Pozzobon"},"content":{"rendered":"\n<p>Desde 2019, o Museu das Mem\u00f3rias (\ud835\ude10\ud835\ude2f)Poss\u00edveis promove o GRUPO DE TRABALHO \u201cTRAUMA E MEM\u00d3RIA: INTERLOCU\u00c7\u00d5ES\u201d.&nbsp;<\/p>\n\n\n\n<p>Neste ano de 2024, estaremos com uma s\u00e9rie de eventos destinados a descomemorar os 60 anos do golpe empresarial-militar de 1964.&nbsp;<\/p>\n\n\n\n<p>Nossos encontros s\u00e3o todas as primeiras segundas-feiras de cada m\u00eas, \u00e0s 21hs, no formato online. S\u00e3o atividades abertas e gratuitas mediante inscri\u00e7\u00e3o.<\/p>\n\n\n\n<p>Em julho temos a honra de receber Cristina Pozzobon, com a fala intitulada&nbsp;<strong>Lugares de mem\u00f3ria e esquecimento.<\/strong><\/p>\n\n\n\n<p>Biografia: \u00c9 artista pl\u00e1stica, designer e jornalista. Realizou 33 obras dos memoriais em homenagem \u00e0s v\u00edtimas da ditadura civil-militar , no per\u00edodo de 1964 a 1985, Direito \u00e0 Mem\u00f3ria e \u00e0 Verdade \u2013 Pessoas Imprescind\u00edveis, Trilhas da Anistia \u2013 Monumento ao Nunca mais; produziu a exposi\u00e7\u00e3o Direito \u00e0 Mem\u00f3ria e \u00e0 Verdade \u2013 Ditadura Militar no Brasil, 1964-1985, desenvolveu a expografia para a mostra Anistia e Democracia \u2013 Para Que N\u00e3o Se Esque\u00e7a Para Que Nunca Mais Aconte\u00e7a e Aus\u00eancias Brasil.&nbsp; Coordena a Ag\u00eancia Livre para Informa\u00e7\u00e3o, Cidadania e Educa\u00e7\u00e3o (Alice), OSC que desenvolve projetos alternativos e aut\u00f4nomos por meio da comunica\u00e7\u00e3o, nas \u00e1reas dos direitos humanos, da mem\u00f3ria e verdade, da justi\u00e7a social e de g\u00eanero, das pol\u00edticas antirracistas, junto \u00e0s popula\u00e7\u00f5es ignoradas pela m\u00eddia tradicional e negligenciadas pelas pol\u00edticas p\u00fablicas.&nbsp;<\/p>\n\n\n\n<p>Quando?<br>1\/07\/2024 | 21h<br>Evento Online<br>Inscri\u00e7\u00f5es: <a href=\"mailto:appoa@appoa.org.br\">appoa@appoa.org.br<\/a><\/p>\n","protected":false},"template":"","_links":{"self":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento\/1130"}],"collection":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento"}],"about":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/types\/acontecimento"}],"wp:attachment":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/media?parent=1130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}