

{"id":106,"date":"2020-10-26T23:40:00","date_gmt":"2020-10-27T02:40:00","guid":{"rendered":"http:\/\/museu.appoa.org.br\/site\/?post_type=acontecimento&#038;p=106"},"modified":"2022-01-19T11:37:07","modified_gmt":"2022-01-19T14:37:07","slug":"acontecimento-1","status":"publish","type":"acontecimento","link":"https:\/\/museu.appoa.org.br\/site\/acontecimento\/acontecimento-1\/","title":{"rendered":"Ler as cinzas \u2013 Trauma, mem\u00f3ria e esperan\u00e7a"},"content":{"rendered":"\r\n<p>Entre os dias 26 e 30 de outubro de 2020 ocorreu o X Semin\u00e1rio Internacional Mem\u00f3ria e Patrim\u00f4nio, organizado pelo N\u00facleo de Estudos sobre Mem\u00f3ria e Patrim\u00f4nio em Lugares de Sofrimento, vinculado ao Programa de P\u00f3s Gradua\u00e7\u00e3o em Mem\u00f3ria Social e Patrim\u00f4nio Cultural da UFPel. O Museu das Mem\u00f3rias (<em>In<\/em>)Poss\u00edveis teve sua presen\u00e7a representada pelo seu coordenador Dr. Edson Luiz Andr\u00e9 de Sousa que proferiu a palestra: \u201cLer as cinzas \u2013 Trauma, mem\u00f3ria e esperan\u00e7a\u201d.<\/p>\r\n<p>A palestra est\u00e1 dispon\u00edvel no Youtube: <a href=\"https:\/\/youtu.be\/X4bog4xqE6s\">https:\/\/youtu.be\/X4bog4xqE6s<\/a>\u00a0<\/p>\r\n<p>&nbsp;<\/p>\r\n","protected":false},"template":"","_links":{"self":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento\/106"}],"collection":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/acontecimento"}],"about":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/types\/acontecimento"}],"wp:attachment":[{"href":"https:\/\/museu.appoa.org.br\/site\/wp-json\/wp\/v2\/media?parent=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}